{"id":25067,"date":"2026-05-03T13:02:45","date_gmt":"2026-05-03T11:02:45","guid":{"rendered":"https:\/\/e-drums.nl\/?p=25067"},"modified":"2026-04-30T15:17:07","modified_gmt":"2026-04-30T13:17:07","slug":"can-i-connect-any-drum-monitor-to-my-e-drum-module","status":"publish","type":"post","link":"https:\/\/e-drums.nl\/en\/kan-ik-elke-drum-monitor-aansluiten-op-mijn-e-drum-module\/","title":{"rendered":"Can I connect any drum monitor to my e-drum module?"},"content":{"rendered":"<p>A question I see frequently is whether you can connect a Roland amp to an Alesis module, or a Millennium amp to a drum kit of another brand, such as Donner or Gear4Music. The short answer is: yes, the brand doesn&#039;t matter. However, there are a few things that are useful to know.<\/p>\n\n\n\n<p>I previously wrote a blog about the best amps: <a href=\"https:\/\/e-drums.nl\/en\/electronic-drum-kit-amplifier-best-buy\/\" data-type=\"post\" data-id=\"4112\">Electronic Drum Kit Amplifier, Best Buy<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Does every monitor work on every module?<\/h2>\n\n\n\n<p>A drum monitor, also known as an amp or amplifier, operates via a standard 6.35mm jack connection (also called a \u00bc\u201d cable or instrument or guitar cable). This cable plugs into a universal connector found on virtually every drum module, regardless of whether it is from Roland, Alesis, Millennium, or another brand.<\/p>\n\n\n\n<p>While brands like Roland and Alesis may design their monitors for their own products, that has more to do with marketing. In practice, you can simply connect a Roland PM-100 to a <a href=\"https:\/\/e-drums.nl\/en\/product\/alesis-nitro-max-kit\/\" data-type=\"product\" data-id=\"4784\">Alesis Nitro Max Kit<\/a>. And a Millennium DM-30 works fine on a Gear4Music kit.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Which monitor is suitable for which module?<\/h2>\n\n\n\n<p>My rule of thumb: choose an amp in the same price range as your drum kit. It is a waste to buy a Roland PM-200 for a budget kit from Millenium or Donner, because the sound won&#039;t come into its own any better than with a cheaper monitor.<\/p>\n\n\n\n<p>It doesn&#039;t work the other way around: If you have a kit in the higher price segment (like most Roland kits and all Efnote kits), make sure you also have a high-quality monitor. Below is an overview:<\/p>\n\n\n\n<p><strong>Budget kits (Donner DED-70, Fazley DDK-020, Millenium Rookie or HD-120)<\/strong> <br>The Millenium DM-30 is a great choice. I have used this monitor myself for multiple gigs and was always very satisfied with it. The output is 30 watts, and it is compact and affordable. For practicing at home and small shows, that is more than sufficient. <\/p>\n\n\n\n<p><strong>Mid-range (Alesis Nitro Max, Millenium MPS-450 or 850, NUX DM-310)<\/strong><br>For the mid-range, the Alesis Strike Amp 8 MK2 is a good option. The monitor is powerful and delivers just that little bit of extra power. At 9.5 kilos, it is also over 5 kilos lighter than the Millenium MD-30. Handy, therefore, for drummers who are often on the go.<\/p>\n\n\n\n<p><strong>Advanced (Roland TD series, Yamaha DTX8K\/10K, all Efnote kits)<\/strong> <br>For drum kits in the higher price segment, the Roland PM-200 or Alesis Strike Amp 12 MK2 is the most suitable choice. The monitor has a power output of 180W RMS, though you won&#039;t even use half of that when drumming at home. This power only becomes truly relevant during gigs or rehearsals with a band.<\/p>\n\n\n\n<p>For home drummers, 180W RMS is easily more than enough. You will never use half of it. That power only becomes truly relevant for small gigs or band rehearsals.<\/p>\n\n\n<div class=\"cegg5-container cegg-offers_grid\"><div class=\"container px-0 mb-5 mt-1\" >\n    <div class=\"row g-3 row-cols-2 row-cols-md-3\">\n        \n                        \n<div class=\"col\">\n    <div class=\"cegg-grid-card cegg-card h-100 p-3 position-relative\">\n\n        \n        <div class=\"cegg-badge-left cegg-badge-secondary text-bg-secondary cegg-badge-sm\">Most economical option<\/div>\n        \n                                <div class=\"ratio ratio-1x1\">\n                <img class=\"card-img-top object-fit-scale rounded\" src=\"https:\/\/www.thomann.de\/prodbilder\/137566.jpg\" decoding=\"async\" loading=\"lazy\" alt=\"Millenium DM-30 Drum Monitor\" \/>            <\/div>\n        \n        <div class=\"card-body p-0 mt-2\">\n                            <div class=\"cegg-merchant small fs-6 text-body-secondary text-truncate\">\n                    <small>Thomann<\/small>\n                <\/div>\n            \n            \n            \n            \n                            <div class=\"card-title fs-6 fw-normal lh-base cegg-hover-title cegg-text-truncate-2 pt-2\">Millenium DM-30 Drum Monitor<\/div>            \n            \n                            <div class=\"cegg-desc-small card-text small lh-sm pt-3\">Suitable for budget drum sets. Can be used for very small gigs and practicing at home.<\/div>\n            \n        <\/div>\n                    \n            <div class=\"cegg-card-button pt-3 position-static\">\n                <div class=\"d-grid\">\n                                            \n                        <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.thomann.de\/intl\/millenium_dm30_drum_monitor.htm?affid=2630&amp;utm_medium=affiliate&amp;offid=1&amp;subid=kan-ik-elke-drum-monitor-aansluiten-op-mijn-e-drum-module&amp;subid2=contentegg\" class=\"stretched-link btn btn-primary\">Go to Thomann<\/a>                                    <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n        \n                        \n<div class=\"col\">\n    <div class=\"cegg-grid-card cegg-card h-100 p-3 position-relative\">\n\n        \n        <div class=\"cegg-badge-left cegg-badge-danger text-bg-danger cegg-badge-sm\">Lightweight<\/div>\n        \n                                <div class=\"ratio ratio-1x1\">\n                <img class=\"card-img-top object-fit-scale rounded\" src=\"https:\/\/www.thomann.de\/prodbilder\/588056.jpg\" decoding=\"async\" loading=\"lazy\" alt=\"Alesis Strike Amp 8 MK2\" \/>            <\/div>\n        \n        <div class=\"card-body p-0 mt-2\">\n                            <div class=\"cegg-merchant small fs-6 text-body-secondary text-truncate\">\n                    <small>Thomann<\/small>\n                <\/div>\n            \n            \n            \n            \n                            <div class=\"card-title fs-6 fw-normal lh-base cegg-hover-title cegg-text-truncate-2 pt-2\">Alesis Strike Amp 8 MK2<\/div>            \n            \n                            <div class=\"cegg-desc-small card-text small lh-sm pt-3\">Lightweight monitor with sufficient power for small shows<\/div>\n            \n        <\/div>\n                    \n            <div class=\"cegg-card-button pt-3 position-static\">\n                <div class=\"d-grid\">\n                                            \n                        <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.thomann.de\/intl\/alesis_strike_amp_8_mk2.htm?affid=2630&amp;utm_medium=affiliate&amp;offid=1&amp;subid=kan-ik-elke-drum-monitor-aansluiten-op-mijn-e-drum-module&amp;subid2=contentegg\" class=\"stretched-link btn btn-primary\">Go to Thomann<\/a>                                    <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n        \n                        \n<div class=\"col\">\n    <div class=\"cegg-grid-card cegg-card h-100 p-3 position-relative\">\n\n        \n        <div class=\"cegg-badge-left cegg-badge-warning text-bg-warning cegg-badge-sm\">Highest quality<\/div>\n        \n                                <div class=\"ratio ratio-1x1\">\n                <img class=\"card-img-top object-fit-scale rounded\" src=\"https:\/\/www.thomann.de\/prodbilder\/430073.jpg\" decoding=\"async\" loading=\"lazy\" alt=\"Roland PM-200 Personal Drum Monitor\" \/>            <\/div>\n        \n        <div class=\"card-body p-0 mt-2\">\n                            <div class=\"cegg-merchant small fs-6 text-body-secondary text-truncate\">\n                    <small>Thomann<\/small>\n                <\/div>\n            \n            \n            \n            \n                            <div class=\"card-title fs-6 fw-normal lh-base cegg-hover-title cegg-text-truncate-2 pt-2\">Roland PM-200 Personal Drum Monitor<\/div>            \n            \n                            <div class=\"cegg-desc-small card-text small lh-sm pt-3\">Suitable for performances and full band rehearsals<\/div>\n            \n        <\/div>\n                    \n            <div class=\"cegg-card-button pt-3 position-static\">\n                <div class=\"d-grid\">\n                                            \n                        <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.thomann.de\/intl\/roland_pm_200_personal_drum_monitor.htm?affid=2630&amp;utm_medium=affiliate&amp;offid=1&amp;subid=kan-ik-elke-drum-monitor-aansluiten-op-mijn-e-drum-module&amp;subid2=contentegg\" class=\"stretched-link btn btn-primary\">Go to Thomann<\/a>                                    <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n            <\/div>\n    \n    <div class=\"row g-2 fst-italic text-body-secondary mt-2 lh-1\">\n                            <div class=\"col-12 col-md-auto cegg-block-disclaimer\">\n                <small>This is an affiliate link. If you buy through this link, I receive a small commission, at no extra cost to you.<\/small>\n            <\/div>\n            <\/div>\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p>The good news, therefore, is that all drum monitors work on all electronic drum kits. However, it is important to consider the quality and power of the monitor and what suits your kit. <\/p>","protected":false},"excerpt":{"rendered":"<p>Een vraag die ik regelmatig voorbij zie komen is of je een Roland amp kan aansluiten op een Alesis module, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[301,171],"tags":[373],"class_list":["post-25067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accessoires-en-uitrusting","category-tips-en-advies","tag-uitgelichte-blogs"],"jetpack_featured_media_url":"https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1.png","spectra_custom_meta":{"_edit_lock":["1777557544:4"],"rank_math_internal_links_processed":["1"],"rank_math_seo_score":["69"],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["set"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_edit_last":["4"],"_cegg_data_Feed__1":["a:3:{i:137566;a:51:{s:9:\"unique_id\";s:6:\"137566\";s:9:\"module_id\";s:7:\"Feed__1\";s:5:\"title\";s:28:\"Millenium DM-30 Drum Monitor\";s:11:\"description\";s:90:\"Geschikt voor budget drumstellen. Te gebruiken voor zeer kleine optredens en thuis oefenen\";s:3:\"img\";s:44:\"https:\/\/www.thomann.de\/prodbilder\/137566.jpg\";s:3:\"url\";s:99:\"https:\/\/www.thomann.de\/intl\/millenium_dm30_drum_monitor.htm?affid=2630&utm_medium=affiliate&offid=1\";s:6:\"domain\";s:7:\"thomann\";s:11:\"last_update\";s:10:\"1778692684\";s:5:\"extra\";s:0:\"\";s:9:\"order_num\";i:1;s:5:\"price\";s:3:\"149\";s:8:\"priceOld\";s:1:\"0\";s:15:\"percentageSaved\";i:0;s:8:\"currency\";s:6:\"&euro;\";s:12:\"currencyCode\";s:3:\"EUR\";s:12:\"manufacturer\";s:9:\"Millenium\";s:8:\"category\";s:0:\"\";s:12:\"categoryPath\";a:0:{}s:8:\"merchant\";s:0:\"\";s:4:\"logo\";s:0:\"\";s:6:\"rating\";s:0:\"\";s:13:\"ratingDecimal\";s:0:\"\";s:12:\"reviewsCount\";s:0:\"\";s:12:\"availability\";s:8:\"in_stock\";s:8:\"orig_url\";s:94:\"https:\/\/www.thomann.nl\/millenium_dm30_drum_monitor.htm?affid=2630&utm_medium=affiliate&offid=1\";s:10:\"bridge_url\";s:0:\"\";s:7:\"aff_url\";s:0:\"\";s:3:\"ean\";s:13:\"4047371375661\";s:5:\"promo\";s:0:\"\";s:3:\"upc\";s:0:\"\";s:3:\"sku\";s:0:\"\";s:4:\"isbn\";s:0:\"\";s:17:\"short_description\";s:0:\"\";s:13:\"shipping_cost\";s:1:\"0\";s:5:\"badge\";s:22:\"Meest voordelige optie\";s:11:\"badge_color\";s:9:\"secondary\";s:8:\"subtitle\";s:0:\"\";s:8:\"woo_sync\";s:0:\"\";s:8:\"woo_attr\";s:0:\"\";s:8:\"features\";a:0:{}s:6:\"images\";a:0:{}s:12:\"stock_status\";s:1:\"1\";s:9:\"img_large\";s:0:\"\";s:5:\"group\";s:0:\"\";s:15:\"_priceFormatted\";N;s:18:\"_priceOldFormatted\";N;s:16:\"_descriptionText\";N;s:7:\"keyword\";s:22:\"millenium dm30 monitor\";s:5:\"added\";s:1:\"1\";s:14:\"target_post_id\";s:0:\"\";s:7:\"post_id\";s:5:\"25067\";}i:588056;a:51:{s:9:\"unique_id\";s:6:\"588056\";s:9:\"module_id\";s:7:\"Feed__1\";s:5:\"title\";s:23:\"Alesis Strike Amp 8 MK2\";s:11:\"description\";s:61:\"Lichtgewicht monitor met voldoende vermogen voor kleine shows\";s:3:\"img\";s:44:\"https:\/\/www.thomann.de\/prodbilder\/588056.jpg\";s:3:\"url\";s:95:\"https:\/\/www.thomann.de\/intl\/alesis_strike_amp_8_mk2.htm?affid=2630&utm_medium=affiliate&offid=1\";s:6:\"domain\";s:7:\"thomann\";s:11:\"last_update\";s:10:\"1778692684\";s:5:\"extra\";s:0:\"\";s:9:\"order_num\";i:2;s:5:\"price\";s:3:\"289\";s:8:\"priceOld\";s:1:\"0\";s:15:\"percentageSaved\";i:0;s:8:\"currency\";s:6:\"&euro;\";s:12:\"currencyCode\";s:3:\"EUR\";s:12:\"manufacturer\";s:6:\"Alesis\";s:8:\"category\";s:0:\"\";s:12:\"categoryPath\";a:0:{}s:8:\"merchant\";s:0:\"\";s:4:\"logo\";s:0:\"\";s:6:\"rating\";s:0:\"\";s:13:\"ratingDecimal\";s:0:\"\";s:12:\"reviewsCount\";s:0:\"\";s:12:\"availability\";s:8:\"in_stock\";s:8:\"orig_url\";s:90:\"https:\/\/www.thomann.nl\/alesis_strike_amp_8_mk2.htm?affid=2630&utm_medium=affiliate&offid=1\";s:10:\"bridge_url\";s:0:\"\";s:7:\"aff_url\";s:0:\"\";s:3:\"ean\";s:13:\"0694318026212\";s:5:\"promo\";s:0:\"\";s:3:\"upc\";s:0:\"\";s:3:\"sku\";s:0:\"\";s:4:\"isbn\";s:0:\"\";s:17:\"short_description\";s:0:\"\";s:13:\"shipping_cost\";s:1:\"0\";s:5:\"badge\";s:12:\"Lichtgewicht\";s:11:\"badge_color\";s:6:\"danger\";s:8:\"subtitle\";s:0:\"\";s:8:\"woo_sync\";s:0:\"\";s:8:\"woo_attr\";s:0:\"\";s:8:\"features\";a:0:{}s:6:\"images\";a:0:{}s:12:\"stock_status\";s:1:\"1\";s:9:\"img_large\";s:0:\"\";s:5:\"group\";s:0:\"\";s:15:\"_priceFormatted\";N;s:18:\"_priceOldFormatted\";N;s:16:\"_descriptionText\";N;s:7:\"keyword\";s:23:\"Alesis Strike Amp 8 MK2\";s:5:\"added\";s:1:\"1\";s:14:\"target_post_id\";s:0:\"\";s:7:\"post_id\";s:5:\"25067\";}i:430073;a:51:{s:9:\"unique_id\";s:6:\"430073\";s:9:\"module_id\";s:7:\"Feed__1\";s:5:\"title\";s:35:\"Roland PM-200 Personal Drum Monitor\";s:11:\"description\";s:53:\"Geschikt voor optredens en volwaardige bandrepetities\";s:3:\"img\";s:44:\"https:\/\/www.thomann.de\/prodbilder\/430073.jpg\";s:3:\"url\";s:107:\"https:\/\/www.thomann.de\/intl\/roland_pm_200_personal_drum_monitor.htm?affid=2630&utm_medium=affiliate&offid=1\";s:6:\"domain\";s:7:\"thomann\";s:11:\"last_update\";s:10:\"1778692684\";s:5:\"extra\";s:0:\"\";s:9:\"order_num\";i:3;s:5:\"price\";s:3:\"535\";s:8:\"priceOld\";s:1:\"0\";s:15:\"percentageSaved\";i:0;s:8:\"currency\";s:6:\"&euro;\";s:12:\"currencyCode\";s:3:\"EUR\";s:12:\"manufacturer\";s:6:\"Roland\";s:8:\"category\";s:0:\"\";s:12:\"categoryPath\";a:0:{}s:8:\"merchant\";s:0:\"\";s:4:\"logo\";s:0:\"\";s:6:\"rating\";s:0:\"\";s:13:\"ratingDecimal\";s:0:\"\";s:12:\"reviewsCount\";s:0:\"\";s:12:\"availability\";s:12:\"out_of_stock\";s:8:\"orig_url\";s:102:\"https:\/\/www.thomann.nl\/roland_pm_200_personal_drum_monitor.htm?affid=2630&utm_medium=affiliate&offid=1\";s:10:\"bridge_url\";s:0:\"\";s:7:\"aff_url\";s:0:\"\";s:3:\"ean\";s:13:\"4957054511890\";s:5:\"promo\";s:0:\"\";s:3:\"upc\";s:0:\"\";s:3:\"sku\";s:0:\"\";s:4:\"isbn\";s:0:\"\";s:17:\"short_description\";s:0:\"\";s:13:\"shipping_cost\";s:1:\"0\";s:5:\"badge\";s:17:\"Hoogste kwaliteit\";s:11:\"badge_color\";s:7:\"warning\";s:8:\"subtitle\";s:0:\"\";s:8:\"woo_sync\";s:0:\"\";s:8:\"woo_attr\";s:0:\"\";s:8:\"features\";a:0:{}s:6:\"images\";a:0:{}s:12:\"stock_status\";s:2:\"-1\";s:9:\"img_large\";s:0:\"\";s:5:\"group\";s:0:\"\";s:15:\"_priceFormatted\";N;s:18:\"_priceOldFormatted\";N;s:16:\"_descriptionText\";N;s:7:\"keyword\";s:13:\"Roland PM-200\";s:5:\"added\";s:1:\"1\";s:14:\"target_post_id\";s:0:\"\";s:7:\"post_id\";s:5:\"25067\";}}"],"_cegg_last_bykeyword_updateFeed__1":["1777545898"],"_cegg_last_update_Feed__1":["1778692684"],"_cegg_offers_count":["2"],"rank_math_primary_category":["301"],"rank_math_focus_keyword":["monitor"],"_thumbnail_id":["25079"],"_uag_css_file_name":["uag-css-25067.css"],"_uag_js_file_name":["uag-js-25067.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:116430:\"\ufeff.uagb-post-grid{margin:0 auto;position:relative}.uagb-post-grid:not(.is-grid) .uagb-post__inner-wrap{background-clip:content-box !important}.uagb-post-grid .uagb-post__inner-wrap{transition:box-shadow .2s ease;overflow:hidden}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.default{margin:5px 5px 5px 0}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{background:#444;color:#fff;border-radius:2px;flex-direction:row;align-items:flex-end;padding:6px 8px;line-height:1;margin-right:5px;margin-bottom:20px}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color:#fff}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy a{text-decoration:none;color:inherit}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__image .uagb-post__image-equal-height{display:block;height:0;padding-bottom:66.67%;overflow:hidden}.uagb-post-grid .uagb-post__load-more-wrap{width:100%;position:absolute;bottom:-30px}.uagb-post-grid .uagb-post__load-more-wrap .uagb-post-pagination-button{cursor:pointer}.uagb-post-grid .uagb-post__load-more-wrap a{color:inherit}.uagb-post-grid.is-grid article{float:left;display:inline-block}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:nth-last-child(2){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:last-child{position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(3){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(2){position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__inner-wrap,.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a{display:block;height:0;overflow:hidden;position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-2-3{padding-bottom:66%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-9-16{padding-bottom:56.25%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-2{padding-bottom:50%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-1{padding-bottom:67%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit{padding-bottom:0;height:auto}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit img{position:unset !important}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a[class^=uagb-image-ratio-]>img{position:absolute;height:100%}.uagb-post-grid.uagb-post__items.is-masonry{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap}.uagb-post-grid.uagb-post__items.is-carousel{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap;width:100%;visibility:hidden}.uagb-post-grid.is-grid .uagb-post__inner-wrap{height:max-content}.uagb-post-grid.is-grid.uagb-post__equal-height .uagb-post__inner-wrap{height:auto}.uagb-post-grid.is-masonry .uagb-post__inner-wrap{height:auto}.uagb-post-grid .uagb-post__author span,.uagb-post-grid .uagb-post__comment span,.uagb-post-grid .uagb-post__taxonomy span,.uagb-post-grid .uagb-post__date span{font-size:inherit;line-height:inherit;width:inherit;height:inherit;margin-right:4px;vertical-align:bottom}.uagb-post-grid.uagb-post__columns-8:not(.is-grid) article{width:12.5%}.uagb-post-grid.uagb-post__columns-7:not(.is-grid) article{width:14.28%}.uagb-post-grid.uagb-post__columns-6:not(.is-grid) article{width:16.66%}.uagb-post-grid.uagb-post__columns-5:not(.is-grid) article{width:20%}.uagb-post-grid.uagb-post__columns-4:not(.is-grid) article{width:25%}.uagb-post-grid.uagb-post__columns-3:not(.is-grid) article{width:33.33%}.uagb-post-grid.uagb-post__columns-2:not(.is-grid) article{width:50%}.uagb-post-grid.uagb-post__columns-1:not(.is-grid) article{width:100%}@media only screen and (max-width: 600px){.uagb-post-grid div[class*=columns].is-grid{grid-template-columns:1fr}}.uagb-post-grid .uagb-post__image img{display:block;width:100%;height:auto;max-width:100%}.uagb-post-grid .uagb-post__title{margin-top:0;margin-bottom:0;word-break:break-word}.uagb-post-grid .uagb-post__title a{color:inherit;box-shadow:none;transition:.3s ease;text-decoration:none}.uagb-post-grid .uagb-post__title a:hover{text-decoration:none}.uagb-post-grid .uagb-post__title a:focus{text-decoration:none}.uagb-post-grid .uagb-post__title a:active{text-decoration:none}.uagb-post-grid .uagb-post-grid-byline>*{margin-right:10px}.uagb-post-grid .uagb-post-grid-byline,.uagb-post-grid .uagb-post__taxonomy{text-transform:capitalize;font-size:14px;font-weight:500;line-height:23px;text-decoration:none}.uagb-post-grid .uagb-post-grid-byline a,.uagb-post-grid .uagb-post-grid-byline a:focus,.uagb-post-grid .uagb-post-grid-byline a:active{color:inherit;font-size:inherit;text-decoration:none}.uagb-post-grid .uagb-post__title a,.uagb-post-grid .uagb-post__title a:focus,.uagb-post-grid .uagb-post__title a:active{color:inherit;font-size:inherit}.uagb-post-grid .uagb-post__author,.uagb-post-grid .uagb-post__date,.uagb-post-grid .uagb-post__comment{display:inline-block;word-break:break-all}.uagb-post-grid .uagb-post__author:not(:last-child)::after,.uagb-post-grid .uagb-post__date:not(:last-child)::after,.uagb-post-grid .uagb-post__comment:not(:last-child)::after{content:\"\u00b7\";vertical-align:middle;align-self:center;margin:0 5px;line-height:1}.uagb-post-grid .uagb-post__comment,.uagb-post-grid .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__author a{box-shadow:none}.uagb-post-grid .uagb-post__author a:hover{color:inherit;box-shadow:0 -1px 0 inset}.uagb-post-grid .uagb-post__excerpt{word-break:break-word}.uagb-post-grid .uagb-post__inner-wrap p:last-of-type{margin-bottom:0}.uagb-post-grid .uagb-post__cta{border:none;display:inline-block;background:none}.uagb-post-grid .uagb-post__cta .ast-outline-button{display:inline-flex}.uagb-post-grid .uagb-post__excerpt p{color:inherit}.is-grid.uagb-post__items{display:grid}.wp-block-uagb-post-grid .uagb-post-pagination-wrap{grid-column:1\/-1}.uagb-post__image-position-background .uagb-post__link-complete-box{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.uagb-post__image-position-background.uagb-post__image-enabled .uagb-post__text{color:#fff}.uagb-post__image-position-background .uagb-post__text{opacity:1;position:relative;z-index:10;overflow:hidden}.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative;width:100%}.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted,.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.default{position:relative;z-index:999}.uagb-post__image-position-background .uagb-post__image img{position:absolute;width:auto;height:auto;min-width:100%;max-width:none;left:50%;top:50%;transform:translate(-50%, -50%);min-height:100%}.uagb-post__image-position-background .uagb-post__image{background-size:cover;background-repeat:no-repeat;background-position:center;overflow:hidden;text-align:center;position:absolute;left:0;top:0;width:100%;height:100%;z-index:2}.uagb-post__image-position-background .uagb-post__image::before{content:\"\";position:absolute;left:0;top:0;width:100%;height:100%;z-index:1;background-color:hsla(0,0%,100%,.5)}.uagb-slick-carousel .is-carousel{padding:0}.uagb-slick-carousel ul.slick-dots{transform:unset;position:relative;padding:unset}.uagb-slick-carousel .slick-prev:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel .slick-next:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel ul.slick-dots li button:not(:hover):not(:active):not(.has-background){background-color:unset}.uagb-post-grid[data-equal-height=yes] .uagb-post__inner-wrap{display:inline-block;height:100%}.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;right:auto}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:-45px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:auto;right:-45px}.uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:25px;z-index:1}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:auto;right:25px}.uagb-post__arrow-inside.uagb-post-grid .slick-next{right:25px}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-next{left:25px;right:auto}.uagb-post-grid.is-grid article,.uagb-post-grid.is-masonry article,.uagb-post-grid.is-carousel article{box-sizing:border-box}@media(max-width: 976px){.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:15px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:auto;right:15px}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:15px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:15px;right:auto}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-8 article{width:12.5%}}@media(max-width: 767px){:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-8 article{width:12.5%}}.entry .entry-content .uagb-post-grid a{text-decoration:none}.uagb-post-pagination-wrap{display:flex;width:100%;flex-wrap:wrap}.uagb-post-pagination-wrap a.page-numbers,.uagb-post-pagination-wrap span.page-numbers.current{padding:5px 10px;margin:0;display:flex;margin-right:4px;margin-bottom:5px}.uagb-post-grid .uagb-post-inf-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.uagb-post-grid .uagb-post-inf-loader div{width:18px;height:18px;background-color:#0085ba;-webkit-border-radius:100%;border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-next{right:0}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;box-shadow: 0px 0px 0 #00000070;}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: -20px;margin-right: -20px;margin-top: -20px;}.uagb-block-46c61df4:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:last-child{margin-bottom: 20px;}.uagb-block-46c61df4:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:first-child{margin-top: 20px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__text:nth-last-child(2) {margin-bottom: 20px;}.uagb-block-46c61df4:not(.wp-block-uagb-post-carousel):not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-46c61df4:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text{margin-left: 20px;margin-right: 20px;}.uagb-block-46c61df4 .uagb-post__inner-wrap{background: #ededed;text-align: left;}.uagb-block-46c61df4 .uagb-post__inner-wrap .uagb-post__cta{padding-bottom: 0px;}.uagb-block-46c61df4 .uagb-post__image {padding-bottom: 15px;}.uagb-block-46c61df4 .uagb-post__title{padding-bottom: 15px;}.uagb-block-46c61df4 .uagb-post-grid-byline{padding-bottom: 15px;}.uagb-block-46c61df4 .uagb-post__excerpt{padding-bottom: 25px;}.uagb-block-46c61df4 .uagb-post__image:before{background-color: #000000;opacity: 0.5;}.uagb-block-46c61df4.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-46c61df4.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-46c61df4 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{color: #fff;background: #3182ce;}.uagb-block-46c61df4 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color: #fff;}.uagb-block-46c61df4.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: none;border-style: none;}.uagb-block-46c61df4 .uagb-post-pagination-wrap{margin-top: 20px;justify-content: left;margin-left: 10px;}.uagb-block-46c61df4 .uagb-post-pagination-wrap .page-numbers.current{background-color: #e4e4e4;color: #333333;}.uagb-block-46c61df4 .uagb-post-pagination-wrap a{background-color: #e4e4e4;color: #777777;}.uagb-block-46c61df4.uagb-equal_height_inline-read-more-buttons .uagb-post__inner-wrap .uagb-post__text:last-child{left: 20px;right: 20px;}.uagb-block-46c61df4.wp-block-uagb-post-grid .uag-post-grid-wrapper{padding-right: 20px;padding-left: 20px;width: 100%;display: flex;flex-direction: column;justify-content: center;}@media only screen and (max-width: 976px) {.uagb-block-46c61df4.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(2 , minmax(0, 1fr));}.uagb-block-46c61df4.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-46c61df4.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-46c61df4 .uagb-post__cta a{border-style: none;}}@media only screen and (max-width: 767px) {.uagb-block-46c61df4.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-46c61df4.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-46c61df4.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-46c61df4.wp-block-uagb-post-grid .uag-post-grid-wrapper{width: unset;}}.uagb-block-3d569773.is-grid .uagb-post__inner-wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;box-shadow: 0px 0px 0 #00000070;}.uagb-block-3d569773.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: -20px;margin-right: -20px;margin-top: -20px;}.uagb-block-3d569773:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:last-child{margin-bottom: 20px;}.uagb-block-3d569773:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:first-child{margin-top: 20px;}.uagb-block-3d569773:not(.is-grid).uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__text:nth-last-child(2) {margin-bottom: 20px;}.uagb-block-3d569773:not(.wp-block-uagb-post-carousel):not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-3d569773:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-3d569773:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text{margin-left: 20px;margin-right: 20px;}.uagb-block-3d569773 .uagb-post__inner-wrap{background: #ededed;text-align: left;}.uagb-block-3d569773 .uagb-post__inner-wrap .uagb-post__cta{padding-bottom: 0px;}.uagb-block-3d569773 .uagb-post__image {padding-bottom: 15px;}.uagb-block-3d569773 .uagb-post__title{padding-bottom: 15px;}.uagb-block-3d569773 .uagb-post-grid-byline{padding-bottom: 15px;}.uagb-block-3d569773 .uagb-post__excerpt{padding-bottom: 25px;}.uagb-block-3d569773 .uagb-post__image:before{background-color: #000000;opacity: 0.5;}.uagb-block-3d569773.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-3d569773.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-3d569773.is-grid .uagb-post__inner-wrap:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3d569773 .uagb-post__text.uagb-post__title{font-size: 17px;}.uagb-block-3d569773 .uagb-post__text.uagb-post__title a{font-size: 17px;}.uagb-block-3d569773 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{color: #fff;background: #3182ce;}.uagb-block-3d569773 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color: #fff;}.uagb-block-3d569773.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: none;border-style: none;}.uagb-block-3d569773 .uagb-post-pagination-wrap{margin-top: 20px;justify-content: left;margin-left: 10px;}.uagb-block-3d569773 .uagb-post-pagination-wrap .page-numbers.current{background-color: #e4e4e4;color: #333333;}.uagb-block-3d569773 .uagb-post-pagination-wrap a{background-color: #e4e4e4;color: #777777;}.uagb-block-3d569773.uagb-equal_height_inline-read-more-buttons .uagb-post__inner-wrap .uagb-post__text:last-child{left: 20px;right: 20px;}.uagb-block-3d569773.wp-block-uagb-post-grid .uag-post-grid-wrapper{padding-right: 20px;padding-left: 20px;width: 100%;display: flex;flex-direction: column;justify-content: center;}@media only screen and (max-width: 976px) {.uagb-block-3d569773.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(2 , minmax(0, 1fr));}.uagb-block-3d569773.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-3d569773:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-3d569773:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-3d569773.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-3d569773.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-3d569773 .uagb-post__cta a{border-style: none;}}@media only screen and (max-width: 767px) {.uagb-block-3d569773.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-3d569773.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-3d569773:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-3d569773:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-3d569773.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-3d569773.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-3d569773.wp-block-uagb-post-grid .uag-post-grid-wrapper{width: unset;}}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;box-shadow: 0px 2px 13px -1px #00000070;border-style: none;}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: -20px;margin-right: -20px;margin-top: -20px;}.uagb-block-46c61df4:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:last-child{margin-bottom: 20px;}.uagb-block-46c61df4:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:first-child{margin-top: 20px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__text:nth-last-child(2) {margin-bottom: 20px;}.uagb-block-46c61df4:not(.wp-block-uagb-post-carousel):not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 29px;}.uagb-block-46c61df4:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text{margin-left: 20px;margin-right: 20px;}.uagb-block-46c61df4 .uagb-post__inner-wrap{background: #ffffff;text-align: left;}.uagb-block-46c61df4 .uagb-post__inner-wrap .uagb-post__cta{padding-bottom: 0px;}.uagb-block-46c61df4 .uagb-post__image {padding-bottom: 20px;}.uagb-block-46c61df4 .uagb-post__title{padding-bottom: 15px;}.uagb-block-46c61df4 .uagb-post-grid-byline{padding-bottom: 15px;}.uagb-block-46c61df4 .uagb-post__excerpt{padding-bottom: 25px;}.uagb-block-46c61df4 .uagb-post__image:before{background-color: #000000;opacity: 0.5;}.uagb-block-46c61df4.is-grid.uagb-post__items{row-gap: 20px;column-gap: 29px;}.uagb-block-46c61df4.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-46c61df4 .uagb-post__text.uagb-post__title{color: #000000;}.uagb-block-46c61df4 .uagb-post__text.uagb-post__title a{color: #000000;}.uagb-block-46c61df4 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{color: #fff;background: #3182ce;}.uagb-block-46c61df4 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color: #fff;}.uagb-block-46c61df4.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: none;border-style: none;}.uagb-block-46c61df4 .uagb-post-pagination-wrap{margin-top: 20px;justify-content: left;margin-left: 10px;}.uagb-block-46c61df4 .uagb-post-pagination-wrap .page-numbers.current{background-color: #e4e4e4;color: #333333;}.uagb-block-46c61df4 .uagb-post-pagination-wrap a{background-color: #e4e4e4;color: #777777;}.uagb-block-46c61df4.uagb-equal_height_inline-read-more-buttons .uagb-post__inner-wrap .uagb-post__text:last-child{left: 20px;right: 20px;}.uagb-block-46c61df4.wp-block-uagb-post-grid .uag-post-grid-wrapper{padding-right: 20px;padding-left: 20px;width: 100%;display: flex;flex-direction: column;justify-content: center;}@media only screen and (max-width: 976px) {.uagb-block-46c61df4.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(2 , minmax(0, 1fr));}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap{border-style: none;}.uagb-block-46c61df4.is-grid.uagb-post__items{row-gap: 20px;column-gap: 29px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 29px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-46c61df4.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-46c61df4 .uagb-post__cta a{border-style: none;}}@media only screen and (max-width: 767px) {.uagb-block-46c61df4.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap{border-style: none;}.uagb-block-46c61df4.is-grid.uagb-post__items{row-gap: 20px;column-gap: 29px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 29px;}.uagb-block-46c61df4:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-46c61df4.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-46c61df4.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-46c61df4.wp-block-uagb-post-grid .uag-post-grid-wrapper{width: unset;}}.uagb-block-3d569773.is-grid .uagb-post__inner-wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;box-shadow: 0px 0px 0 #00000070;}.uagb-block-3d569773.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: -20px;margin-right: -20px;margin-top: -20px;}.uagb-block-3d569773:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:last-child{margin-bottom: 20px;}.uagb-block-3d569773:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:first-child{margin-top: 20px;}.uagb-block-3d569773:not(.is-grid).uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__text:nth-last-child(2) {margin-bottom: 20px;}.uagb-block-3d569773:not(.wp-block-uagb-post-carousel):not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-3d569773:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-3d569773:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text{margin-left: 20px;margin-right: 20px;}.uagb-block-3d569773 .uagb-post__inner-wrap{background: #ededed;text-align: left;}.uagb-block-3d569773 .uagb-post__inner-wrap .uagb-post__cta{padding-bottom: 0px;}.uagb-block-3d569773 .uagb-post__image {padding-bottom: 15px;}.uagb-block-3d569773 .uagb-post__title{padding-bottom: 15px;}.uagb-block-3d569773 .uagb-post-grid-byline{padding-bottom: 15px;}.uagb-block-3d569773 .uagb-post__excerpt{padding-bottom: 25px;}.uagb-block-3d569773 .uagb-post__image:before{background-color: #000000;opacity: 0.5;}.uagb-block-3d569773.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-3d569773.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-3d569773.is-grid .uagb-post__inner-wrap:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3d569773 .uagb-post__text.uagb-post__title{font-size: 17px;}.uagb-block-3d569773 .uagb-post__text.uagb-post__title a{font-size: 17px;}.uagb-block-3d569773 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{color: #fff;background: #3182ce;}.uagb-block-3d569773 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color: #fff;}.uagb-block-3d569773.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: none;border-style: none;}.uagb-block-3d569773 .uagb-post-pagination-wrap{margin-top: 20px;justify-content: left;margin-left: 10px;}.uagb-block-3d569773 .uagb-post-pagination-wrap .page-numbers.current{background-color: #e4e4e4;color: #333333;}.uagb-block-3d569773 .uagb-post-pagination-wrap a{background-color: #e4e4e4;color: #777777;}.uagb-block-3d569773.uagb-equal_height_inline-read-more-buttons .uagb-post__inner-wrap .uagb-post__text:last-child{left: 20px;right: 20px;}.uagb-block-3d569773.wp-block-uagb-post-grid .uag-post-grid-wrapper{padding-right: 20px;padding-left: 20px;width: 100%;display: flex;flex-direction: column;justify-content: center;}@media only screen and (max-width: 976px) {.uagb-block-3d569773.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(2 , minmax(0, 1fr));}.uagb-block-3d569773.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-3d569773:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-3d569773:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-3d569773.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-3d569773.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-3d569773 .uagb-post__cta a{border-style: none;}}@media only screen and (max-width: 767px) {.uagb-block-3d569773.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-3d569773.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-3d569773:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-3d569773:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-3d569773.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-3d569773.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-3d569773.wp-block-uagb-post-grid .uag-post-grid-wrapper{width: unset;}}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.uagb-block-136b7411 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-136b7411 .uagb-ifb-icon svg{fill: #333;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-136b7411 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-136b7411 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-136b7411 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-136b7411 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-136b7411.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 45px;margin-left: 0px;margin-right: 0px;}.uagb-block-136b7411.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-136b7411 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-136b7411 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-136b7411 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-136b7411 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-136b7411 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-136b7411.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-136b7411.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-image-content > img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-136b7411 .uagb-ifb-title{font-size: 22px;line-height: 1.5em;}[dir=rtl] .uagb-block-136b7411 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-136b7411.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-136b7411 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-image-content img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-136b7411.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-136b7411 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-136b7411.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-image-content img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-ab21409b.wp-block-uagb-advanced-heading {margin-bottom: -19px;}.wp-block-uagb-advanced-heading.uagb-block-ab21409b.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ab21409b.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ab21409b.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ab21409b.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ab21409b .uagb-heading-text{font-size: 22px;line-height: 1.5em;}\ufeff.uagb-forms__outer-wrap .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-input::placeholder,.uagb-forms__outer-wrap .uagb-forms-input-label,.uagb-forms__outer-wrap .uagb-forms-main-submit-button,.uagb-forms__outer-wrap .uagb-forms-success-message,.uagb-forms__outer-wrap .uagb-forms-failed-message{-webkit-transition-property:color,background-color,border-color;-moz-transition-property:color,background-color,border-color;-o-transition-property:color,background-color,border-color;transition-property:color,background-color,border-color;-webkit-transition-duration:.15s;-moz-transition-duration:.15s;-o-transition-duration:.15s;transition-duration:.15s}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=text]{min-height:0 !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input::-webkit-input-placeholder,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=text]::-webkit-input-placeholder{overflow:unset}.uagb-forms__outer-wrap .uagb-forms-main-form input:not([type=checkbox]):not([type=radio]):not([type=file]),.uagb-forms__outer-wrap .uagb-forms-main-form textarea,.uagb-forms__outer-wrap .uagb-forms-main-form select{width:100%;box-sizing:border-box}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-checkbox-wrap .uagb-form-checkbox-option input.uagb-inner-input-view{width:33%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-forms-phone-input{width:75% !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%;justify-content:space-between}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .required::after{color:red;content:\" *\"}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-form-hidden-data{display:none}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button.wp-block-button__link{width:auto}.uagb-forms__outer-wrap .uagb-forms-submit-message-hide{display:none}.uagb-forms__outer-wrap .uagb-forms-success-message{padding:20px 20px}.uagb-forms__outer-wrap .uagb-forms-failed-message{padding:20px 20px}.uagb-forms__outer-wrap span.components-spinner{float:none}.uagb-forms__outer-wrap .uagb-forms-input.uagb-form-phone-country{background-color:#fff}.uagb-forms__outer-wrap .uag-col-2-wrap{display:grid;grid-template-columns:1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-3-wrap{display:grid;grid-template-columns:1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-4-wrap{display:grid;grid-template-columns:1fr 1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uagb-switch{position:relative;display:inline-block;width:50px;height:25px}.uagb-forms__outer-wrap .uagb-switch input{width:0;height:0;opacity:0}.uagb-forms__outer-wrap .uagb-slider{position:absolute;top:0;right:0;bottom:0;left:0;background-color:#fff;cursor:pointer;transition:.4s;-webkit-transition:.4s}.uagb-forms__outer-wrap .uagb-switch .uagb-slider::before{position:absolute;width:20px;height:20px;background-color:#000;transition:.4s;content:\"\";-webkit-transition:.4s}.uagb-forms__outer-wrap .uagb-switch input:checked+.uagb-slider::before{background-color:#fff}.uagb-forms__outer-wrap .uagb-slider.round::before{border-radius:50% !important}.uagb-forms-select-box,.uagb-form-phone-country,.uagb-forms-phone-wrap .uagb-forms-phone-input{height:auto;-webkit-appearance:none;appearance:none}.uagb-forms-radio-wrap input[type=radio]:checked+label::before{line-height:1.2;content:\" \"}.uagb-forms-radio-wrap input[type=radio]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\"\"}.uagb-forms-radio-wrap input[type=radio].round+label::before{border-radius:100% !important}select::after,select::before{padding:10px}.uagb-forms-radio-wrap input[type=radio],.uagb-forms-checkbox-wrap input[type=checkbox],.uagb-forms-accept-wrap input[type=checkbox]{opacity:0}.uagb-forms-checkbox-wrap input[type=checkbox]:checked+label::before,.uagb-forms-accept-wrap input[type=checkbox]:checked+label::before{line-height:1.2;content:\"\u2714\"}.uagb-forms-checkbox-wrap input[type=checkbox]+label::before,.uagb-forms-accept-wrap input[type=checkbox]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\" \"}@media only screen and (max-width: 767px){.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%}}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-20 .uagb-forms-main-form{column-gap:20px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-15 .uagb-forms-main-form{column-gap:15px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-10 .uagb-forms-main-form{column-gap:10px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-5 .uagb-forms-main-form{column-gap:5px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-flex-start .uagb-forms-main-form{align-items:flex-start}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-center .uagb-forms-main-form{align-items:center}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form{display:flex;flex-wrap:wrap;margin:0 -5px;position:relative;text-align:left}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-80{width:80%}@media(min-width: 768px)and (max-width: 1024px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}@media(max-width: 767px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}.uagb-block-e702f682.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e702f682 .uagb-forms-main-form textarea{text-align: left;}.uagb-block-e702f682 .uagb-forms-input{text-align: left;}.uagb-block-e702f682 .uagb-forms-input-label{display: none;text-align: left;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-field-set{margin-bottom: 20px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;margin-bottom: 10px;}.uagb-block-e702f682 .uagb-forms-success-message{color: var(--ast-global-color-2);}.uagb-block-e702f682 .uagb-forms-failed-message{color: var(--ast-global-color-2);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input:focus{outline:  none !important;background-color:  !important;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input:focus::placeholder{color:  !important;}.uagb-block-e702f682 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-e702f682 .uagb-form-phone-country{background: url(data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PSIwIDAgNTEyIDUxMiIgd2lkdGg9JzE4cHgnIGhlaWdodD0nMThweCcgeG1sOnNwYWNlPSJwcmVzZXJ2ZSIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiBlbmFibGUtYmFja2dyb3VuZD0ibmV3IDAgMCA1MTIgNTEyIj48cGF0aCBkPSJtMzk2LjYgMTYwIDE5LjQgMjAuN0wyNTYgMzUyIDk2IDE4MC43bDE5LjMtMjAuN0wyNTYgMzEwLjV6IiBmaWxsPSIjMWQyMzI3IiBjbGFzcz0iZmlsbC0wMDAwMDAiPjwvcGF0aD48L3N2Zz4=) no-repeat;-moz-appearance: none !important;-webkit-appearance:  none !important;background-position:  top 50% right 12px;appearance: none !important;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: left;}.uagb-block-e702f682 .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-e702f682 .uagb-forms-radio-wrap input[type=radio] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-e702f682 .uagb-slider{background-color: #ffffff;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider:before{height: 20px;width: 20px;top: 3px;bottom: 3px;left: 3px;background-color: #1e1e1e;border-radius: 3px 3px 3px 3px;}.uagb-block-e702f682 .uagb-switch input:checked + .uagb-slider{background-color: #017cba;}.uagb-block-e702f682 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);background-color: #ffffff;}.uagb-block-e702f682 .uagb-switch input:focus + .uagb-slider{box-shadow: 0 0 1px#017cba;}.uagb-block-e702f682 .uagb-forms-accept-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-style: solid;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input.uagb-form-phone-country{padding-top: 11px;padding-bottom: 11px;padding-left: 12px;padding-right: 12px;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-input{padding-top: 12px;padding-bottom: 12px;padding-left: 12px;padding-right: 12px;}.uagb-block-e702f682 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{background-color: #ffffff;box-shadow: inset 0 0 0 4px #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button-wrap.wp-block-button:not(.is-style-outline) .uagb-forms-main-submit-button.wp-block-button__link {font-size: 14px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button {font-size: 14px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-e702f682.uagb-forms__full-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{width: 100%;padding: 10px 15px;}.uagb-block-e702f682.uagb-forms__small-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 5px 10px;}.uagb-block-e702f682.uagb-forms__medium-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 12px 24px;}.uagb-block-e702f682.uagb-forms__large-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 20px 30px;}.uagb-block-e702f682.uagb-forms__extralarge-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 30px 65px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 14px;}@media only screen and (max-width: 976px) {.uagb-block-e702f682.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-e702f682 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-e702f682 .uagb-form-phone-country{background-position: top 50% right 12px;padding-right: 30px;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input{border-style: solid;}.uagb-block-e702f682 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-e702f682 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 15px;}}@media only screen and (max-width: 767px) {.uagb-block-e702f682.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-e702f682 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-e702f682 .uagb-form-phone-country{background-position: top 50% right 6px;padding-right: 30px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{display: grid;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input{border-style: solid;}.uagb-block-e702f682 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-e702f682 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 15px;}}.uagb-block-136b7411 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-136b7411 .uagb-ifb-icon svg{fill: #333;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-136b7411 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-136b7411 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-136b7411 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-136b7411 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-136b7411.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 45px;margin-left: 0px;margin-right: 0px;}.uagb-block-136b7411.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-136b7411 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-136b7411 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-136b7411 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-136b7411 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-136b7411 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-136b7411.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-136b7411.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-image-content > img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-136b7411 .uagb-ifb-title{font-size: 22px;line-height: 1.5em;}[dir=rtl] .uagb-block-136b7411 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-136b7411.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-136b7411 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-image-content img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-136b7411.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-136b7411 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-136b7411 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-136b7411.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-image-content img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 90px;}.uagb-block-136b7411 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 90px;}.uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-136b7411.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-136b7411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-advanced-heading.uagb-block-ab21409b.wp-block-uagb-advanced-heading {margin-bottom: -19px;}.wp-block-uagb-advanced-heading.uagb-block-ab21409b.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ab21409b.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ab21409b.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ab21409b.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ab21409b .uagb-heading-text{font-size: 22px;line-height: 1.5em;}.uagb-block-e702f682.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e702f682 .uagb-forms-main-form textarea{text-align: left;}.uagb-block-e702f682 .uagb-forms-input{text-align: left;}.uagb-block-e702f682 .uagb-forms-input-label{display: none;text-align: left;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-field-set{margin-bottom: 20px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;margin-bottom: 10px;}.uagb-block-e702f682 .uagb-forms-success-message{color: var(--ast-global-color-2);}.uagb-block-e702f682 .uagb-forms-failed-message{color: var(--ast-global-color-2);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input:focus{outline:  none !important;background-color:  !important;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input:focus::placeholder{color:  !important;}.uagb-block-e702f682 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-e702f682 .uagb-form-phone-country{background: url(data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PSIwIDAgNTEyIDUxMiIgd2lkdGg9JzE4cHgnIGhlaWdodD0nMThweCcgeG1sOnNwYWNlPSJwcmVzZXJ2ZSIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiBlbmFibGUtYmFja2dyb3VuZD0ibmV3IDAgMCA1MTIgNTEyIj48cGF0aCBkPSJtMzk2LjYgMTYwIDE5LjQgMjAuN0wyNTYgMzUyIDk2IDE4MC43bDE5LjMtMjAuN0wyNTYgMzEwLjV6IiBmaWxsPSIjMWQyMzI3IiBjbGFzcz0iZmlsbC0wMDAwMDAiPjwvcGF0aD48L3N2Zz4=) no-repeat;-moz-appearance: none !important;-webkit-appearance:  none !important;background-position:  top 50% right 12px;appearance: none !important;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: left;}.uagb-block-e702f682 .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-e702f682 .uagb-forms-radio-wrap input[type=radio] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-e702f682 .uagb-slider{background-color: #ffffff;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider:before{height: 20px;width: 20px;top: 3px;bottom: 3px;left: 3px;background-color: #1e1e1e;border-radius: 3px 3px 3px 3px;}.uagb-block-e702f682 .uagb-switch input:checked + .uagb-slider{background-color: #017cba;}.uagb-block-e702f682 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);background-color: #ffffff;}.uagb-block-e702f682 .uagb-switch input:focus + .uagb-slider{box-shadow: 0 0 1px#017cba;}.uagb-block-e702f682 .uagb-forms-accept-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-style: solid;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input.uagb-form-phone-country{padding-top: 11px;padding-bottom: 11px;padding-left: 12px;padding-right: 12px;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-input{padding-top: 12px;padding-bottom: 12px;padding-left: 12px;padding-right: 12px;}.uagb-block-e702f682 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{background-color: #ffffff;box-shadow: inset 0 0 0 4px #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button-wrap.wp-block-button:not(.is-style-outline) .uagb-forms-main-submit-button.wp-block-button__link {font-size: 14px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button {font-size: 14px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-e702f682.uagb-forms__full-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{width: 100%;padding: 10px 15px;}.uagb-block-e702f682.uagb-forms__small-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 5px 10px;}.uagb-block-e702f682.uagb-forms__medium-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 12px 24px;}.uagb-block-e702f682.uagb-forms__large-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 20px 30px;}.uagb-block-e702f682.uagb-forms__extralarge-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 30px 65px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 14px;}@media only screen and (max-width: 976px) {.uagb-block-e702f682.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-e702f682 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-e702f682 .uagb-form-phone-country{background-position: top 50% right 12px;padding-right: 30px;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input{border-style: solid;}.uagb-block-e702f682 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-e702f682 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 15px;}}@media only screen and (max-width: 767px) {.uagb-block-e702f682.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-e702f682 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-e702f682 .uagb-form-phone-country{background-position: top 50% right 6px;padding-right: 30px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{display: grid;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-input{border-style: solid;}.uagb-block-e702f682 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-e702f682 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-e702f682 .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}.uagb-block-e702f682 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 15px;}}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.uagb-block-b1908514.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-b1908514.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-79d7bca0 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-79d7bca0 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-79d7bca0 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-79d7bca0 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-79d7bca0 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-79d7bca0.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-79d7bca0.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-79d7bca0 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-79d7bca0 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-79d7bca0 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-79d7bca0 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.uagb-block-b1908514.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-b1908514.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-79d7bca0.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-79d7bca0 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}@media only screen and (max-width: 767px) {.uagb-block-b1908514.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-b1908514.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-79d7bca0.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-79d7bca0 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}.uagb-block-dfce4ee2.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-dfce4ee2.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-162e17b8 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-162e17b8 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-162e17b8 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-162e17b8 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-162e17b8 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-162e17b8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-162e17b8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-162e17b8 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-162e17b8 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-162e17b8 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-162e17b8 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.uagb-block-dfce4ee2.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-dfce4ee2.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-162e17b8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-162e17b8 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}@media only screen and (max-width: 767px) {.uagb-block-dfce4ee2.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-dfce4ee2.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-162e17b8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-162e17b8 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}.uagb-cta__outer-wrap .uagb-cta__content,.uagb-cta__outer-wrap a.uagb-cta__block-link span,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__button-wrapper,.uagb-cta__outer-wrap .uagb-cta-typeof-button,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__outer-wrap .uagb-cta-with-svg{display:inline-block}.uagb-cta__outer-wrap{display:flex;justify-content:space-between}.wp-block-uagb-call-to-action .uagb-cta__buttons{display:inline-flex}.wp-block-uagb-call-to-action .wp-block-button__link,.wp-block-uagb-call-to-action .ast-outline-button{fill:currentColor;justify-content:center}.uagb-cta__button-link-wrapper,.uagb-cta-second__button{display:inline-flex;align-items:center;word-break:keep-all;width:100%}.uagb-cta__title{padding:0;margin:0;display:block}.uagb-cta__content-right .uagb-cta__button-wrapper{float:right}.uagb-cta__link-wrapper.uagb-cta__block-link-style:empty{display:none}a.uagb-cta__block-link,.entry .entry-content a.uagb-cta__block-link,a.uagb-cta__block-link-wrap,.entry .entry-content a.uagb-cta__block-link-wrap{text-decoration:none}a.uagb-cta__block-link:hover,.entry .entry-content a.uagb-cta__block-link:hover,a.uagb-cta__block-link-wrap:hover,.entry .entry-content a.uagb-cta__block-link-wrap:hover .entry .entry-content a.uagb-cta__block-link:hover{color:inherit}.uagb-cta__content-right{text-align:right;justify-content:flex-end}.uagb-cta__left-right-wrap{width:100%;word-break:break-word}.uagb-cta__icon-position-below-title .uagb-cta__left-right-wrap{display:block;min-width:100%;width:100%}.uagb-cta__icon-position-left .uagb-cta__left-right-wrap,.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{display:flex}.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{justify-content:flex-end}.uagb-cta__block-link-icon-after{margin-left:5px;margin-right:0}.uagb-cta__block-link-icon-before{margin-left:0;margin-right:5px}.uagb-cta__block-link-icon,.uagb-cta__block svg{transition:all 200ms linear}.uagb-cta__block{position:relative}.uagb-cta-typeof-button{line-height:1;text-align:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__content-right.uagb-cta__button-valign-middle .uagb-cta__left-right-wrap{display:flex;align-items:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link{justify-content:center}.uagb-cta__link-wrapper a{box-shadow:none;text-decoration:none}.uagb-cta__block,.uagb-cta__content,.uagb-cta__left-right-wrap{z-index:1}.uagb-cta__block-link{cursor:pointer}.uagb-cta__content-right .uagb-cta__block-link{float:right;padding:10px 14px}a.uagb-cta__block-link-wrap{color:inherit}.uagb-cta__content p:empty{display:none}.uagb-cta__button-type-none .uagb-cta__content{width:100%}.uagb-cta-with-svg{height:14px;width:14px;line-height:14px;vertical-align:middle}.uagb-cta__block svg{display:block;height:inherit;width:inherit}.uagb-cta__button-link-wrapper svg{width:20px;height:20px}.uagb-cta__align-button-after{margin-left:5px}.uagb-cta__align-button-before{margin-right:5px}.uagb-cta__block-link i{font-style:normal}a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.wp-block-uagb-call-to-action{position:relative}.wp-block-uagb-call-to-action a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}@media only screen and (max-width: 976px){.uagb-cta__content-stacked-tablet,.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}@media screen and (max-width: 767px){.uagb-cta__content-stacked-mobile,.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}.uagb-cta__desc p:last-child{margin-bottom:0}.uagb-block-6c01666d.wp-block-uagb-call-to-action .uagb-cta__title{margin-bottom: 10px;}.uagb-block-6c01666d.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 10px;}.uagb-block-6c01666d .uagb-cta__align-button-after{margin-left: 12px;}.uagb-block-6c01666d .uagb-cta__align-button-before{margin-right: 12px;}.uagb-block-6c01666d .uagb-cta__button-wrapper .uagb-cta-with-svg{font-size: 17px;width: 17px;height: 17px;line-height: 17px;}.uagb-block-6c01666d.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper > svg{margin-left: 12px;font-size: 17px;width: 17px;height: 17px;line-height: 17px;}.uagb-block-6c01666d.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper:hover > svg{fill: #000000;}.uagb-block-6c01666d.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper:focus > svg{fill: #000000;}.uagb-block-6c01666d.wp-block-uagb-call-to-action a.uagb-cta-second__button > svg{margin-left: 10px;font-size: 14px;width: 14px;height: 14px;line-height: 14px;}.uagb-block-6c01666d .uagb-cta__content-wrap{text-align: left;}.uagb-block-6c01666d .uagb-cta__wrap{width: 70%;text-align: left;}.uagb-block-6c01666d.wp-block-uagb-call-to-action{text-align: left;}.uagb-block-6c01666d .uagb-cta__left-right-wrap .uagb-cta__content{margin-left: 0px;}.uagb-block-6c01666d .uagb-cta__buttons{column-gap: 15px;}.uagb-block-6c01666d.wp-block-uagb-call-to-action {display: flex;justify-content: space-between;}.uagb-block-6c01666d .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 70%;}.uagb-block-6c01666d .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-6c01666d.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper {align-self: center;height: fit-content;margin-left: auto;}.uagb-block-6c01666d.wp-block-uagb-call-to-action  {flex-direction: column;align-items: flex-start;}.uagb-block-6c01666d.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button{align-self: center;height: fit-content;}.uagb-block-6c01666d.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:hover{background-color: !important;}.uagb-block-6c01666d.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:focus{background-color: !important;}.uagb-block-6c01666d .uagb-cta__button-wrapper a.uagb-cta-typeof-button{color: #333;background-color: #cf0000;padding-top: 10px;padding-bottom: 10px;padding-left: 15px;padding-right: 15px;border-top-width: 3px;border-left-width: 3px;border-right-width: 3px;border-bottom-width: 3px;border-top-left-radius: 20px;border-top-right-radius: 20px;border-bottom-left-radius: 20px;border-bottom-right-radius: 20px;border-color: #cf0000;border-style: solid;}.uagb-block-6c01666d.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__button-wrapper a.uagb-cta-typeof-button:hover{color: #000000;background-color: #ffffff;border-color: #cf0000;}.uagb-block-6c01666d.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__button-wrapper a.uagb-cta-typeof-button:focus{color: #000000;background-color: #ffffff;border-color: #cf0000;}.uagb-block-6c01666d.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{background-color: #cf0000;padding-top: 10px;padding-bottom: 10px;padding-left: 15px;padding-right: 15px;border-top-width: 3px;border-left-width: 3px;border-right-width: 3px;border-bottom-width: 3px;border-top-left-radius: 20px;border-top-right-radius: 20px;border-bottom-left-radius: 20px;border-bottom-right-radius: 20px;border-color: #cf0000;border-style: solid;}.uagb-block-6c01666d.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link:hover{color: #000000;background-color: #ffffff;border-color: #cf0000;}.uagb-block-6c01666d.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link:focus{color: #000000;background-color: #ffffff;border-color: #cf0000;}.uagb-block-6c01666d.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{font-family: \"Karla\";text-transform: none;font-weight: 500;font-size: 17px;}.uagb-block-6c01666d .uagb-cta__button-wrapper a.uagb-cta__button-link-wrapper{font-family: \"Karla\";text-transform: none;font-weight: 500;font-size: 17px;}.uagb-block-6c01666d.wp-block-uagb-call-to-action a.uagb-cta-second__button{text-transform: normal;text-decoration: none;font-size: 14px;}@media only screen and (max-width: 976px) {.uagb-block-6c01666d.wp-block-uagb-call-to-action.uagb-cta__content-stacked-tablet {display: inherit;}.uagb-block-6c01666d.uagb-cta__content-stacked-tablet .uagb-cta__wrap{width: 100%;}.uagb-block-6c01666d .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-6c01666d .uagb-cta__wrap{text-align: center;}.uagb-block-6c01666d.wp-block-uagb-call-to-action  {flex-direction: column;align-items: center;}.uagb-block-6c01666d.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{border-style: solid;border-color: #cf0000;}.uagb-block-6c01666d.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: solid;border-color: #cf0000;}}@media only screen and (max-width: 767px) {.uagb-block-6c01666d.wp-block-uagb-call-to-action.uagb-cta__content-stacked-mobile {display: inherit;}.uagb-block-6c01666d.uagb-cta__content-stacked-mobile .uagb-cta__wrap{width: 100%;}.uagb-block-6c01666d .uagb-cta__buttons{justify-content: center;}.uagb-block-6c01666d .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-6c01666d .uagb-cta__wrap{text-align: center;}.uagb-block-6c01666d.wp-block-uagb-call-to-action  {flex-direction: column;align-items: center;}.uagb-block-6c01666d.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{border-style: solid;border-color: #cf0000;}.uagb-block-6c01666d.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: solid;border-color: #cf0000;}}\";s:2:\"js\";s:1318:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener(\"DOMContentLoaded\", function(){\n\tUAGBForms.init( {\"block_id\":\"e702f682\",\"reCaptchaEnable\":false,\"reCaptchaType\":\"v2\",\"reCaptchaSiteKeyV2\":\"\",\"reCaptchaSiteKeyV3\":\"\",\"afterSubmitToEmail\":\"abc@gmail.com\",\"afterSubmitCcEmail\":\"\",\"afterSubmitBccEmail\":\"\",\"afterSubmitEmailSubject\":\"Fomulier verzending\",\"sendAfterSubmitEmail\":true,\"confirmationType\":\"message\",\"hidereCaptchaBatch\":false,\"captchaMessage\":\"Gelieve bovenstaande captcha in te vullen.\",\"confirmationUrl\":\"\"}, '.uagb-block-e702f682', 25109 );\n});\nwindow.addEventListener(\"DOMContentLoaded\", function(){\n\tUAGBForms.init( {\"block_id\":\"e702f682\",\"reCaptchaEnable\":false,\"reCaptchaType\":\"v2\",\"reCaptchaSiteKeyV2\":\"\",\"reCaptchaSiteKeyV3\":\"\",\"afterSubmitToEmail\":\"abc@gmail.com\",\"afterSubmitCcEmail\":\"\",\"afterSubmitBccEmail\":\"\",\"afterSubmitEmailSubject\":\"Fomulier verzending\",\"sendAfterSubmitEmail\":true,\"confirmationType\":\"message\",\"hidereCaptchaBatch\":false,\"captchaMessage\":\"Gelieve bovenstaande captcha in te vullen.\",\"confirmationUrl\":\"\"}, '.uagb-block-e702f682', 25109 );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-79d7bca0' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-162e17b8' );\n});\n });\";s:18:\"current_block_list\";a:42:{i:0;s:14:\"core\/paragraph\";i:1;s:12:\"core\/heading\";i:2;s:20:\"content-egg\/products\";i:3;s:10:\"core\/group\";i:4;s:18:\"core\/legacy-widget\";i:5;s:10:\"core\/image\";i:6;s:11:\"core\/search\";i:7;s:17:\"core\/latest-posts\";i:8;s:20:\"core\/latest-comments\";i:9;s:13:\"core\/archives\";i:10;s:15:\"core\/categories\";i:12;s:11:\"core\/spacer\";i:13;s:12:\"core\/buttons\";i:14;s:11:\"core\/button\";i:15;s:21:\"wpforms\/form-selector\";i:16;s:30:\"woocommerce\/product-categories\";i:17;s:28:\"woocommerce\/featured-product\";i:18;s:9:\"core\/list\";i:19;s:14:\"core\/list-item\";i:20;s:10:\"core\/cover\";i:21;s:28:\"ic-epc\/product-search-widget\";i:22;s:26:\"ic-epc\/product-sort-filter\";i:23;s:27:\"ic-epc\/product-price-filter\";i:24;s:30:\"ic-epc\/product-category-filter\";i:25;s:26:\"woocommerce\/filter-wrapper\";i:26;s:26:\"woocommerce\/active-filters\";i:27;s:16:\"core\/widget-area\";i:28;s:14:\"uagb\/post-grid\";i:30;s:28:\"woocommerce\/attribute-filter\";i:32;s:24:\"woocommerce\/price-filter\";i:34;s:13:\"uagb\/info-box\";i:35;s:21:\"uagb\/advanced-heading\";i:36;s:10:\"uagb\/forms\";i:37;s:16:\"uagb\/forms-email\";i:38;s:26:\"woocommerce\/product-search\";i:39;s:12:\"uagb\/buttons\";i:40;s:18:\"uagb\/buttons-child\";i:41;s:19:\"uagb\/call-to-action\";i:42;s:12:\"core\/gallery\";i:43;s:17:\"yarpp\/yarpp-block\";i:44;s:38:\"contextual-related-posts\/related-posts\";i:45;s:14:\"core\/shortcode\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778690886\";s:6:\"gfonts\";a:1:{s:5:\"Karla\";a:2:{s:10:\"fontfamily\";s:5:\"Karla\";s:12:\"fontvariants\";a:1:{i:0;s:3:\"500\";}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"meta_box":[],"uagb_featured_image_src":{"full":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1.png",1536,1024,false],"thumbnail":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-408x305.png",408,305,true],"medium":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-500x333.png",500,333,true],"medium_large":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-768x512.png",768,512,true],"large":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-1024x683.png",1024,683,true],"1536x1536":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1.png",1536,1024,false],"2048x2048":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1.png",1536,1024,false],"trp-custom-language-flag":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-18x12.png",18,12,true],"woocommerce_thumbnail":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-750x750.png",750,750,true],"woocommerce_single":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-1000x667.png",1000,667,true],"woocommerce_gallery_thumbnail":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-100x100.png",100,100,true],"affcoups-thumb":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-480x270.png",480,270,true],"affcoups-thumb-small":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-133x75.png",133,75,true],"woosc-large":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-600x600.png",600,600,true],"woosc-small":["https:\/\/e-drums.nl\/wp-content\/uploads\/2026\/04\/elektronisch-drumstel-monitor-1-96x96.png",96,96,true]},"uagb_author_info":{"display_name":"Kasper","author_link":"https:\/\/e-drums.nl\/en\/author\/kasperstap\/"},"uagb_comment_info":0,"uagb_excerpt":"Een vraag die ik regelmatig voorbij zie komen is of je een Roland amp kan aansluiten op een Alesis module, [&hellip;]","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/e-drums.nl\/en\/wp-json\/wp\/v2\/posts\/25067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-drums.nl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e-drums.nl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e-drums.nl\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/e-drums.nl\/en\/wp-json\/wp\/v2\/comments?post=25067"}],"version-history":[{"count":12,"href":"https:\/\/e-drums.nl\/en\/wp-json\/wp\/v2\/posts\/25067\/revisions"}],"predecessor-version":[{"id":25090,"href":"https:\/\/e-drums.nl\/en\/wp-json\/wp\/v2\/posts\/25067\/revisions\/25090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-drums.nl\/en\/wp-json\/wp\/v2\/media\/25079"}],"wp:attachment":[{"href":"https:\/\/e-drums.nl\/en\/wp-json\/wp\/v2\/media?parent=25067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e-drums.nl\/en\/wp-json\/wp\/v2\/categories?post=25067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e-drums.nl\/en\/wp-json\/wp\/v2\/tags?post=25067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}